{"id":3376,"date":"2025-09-05T17:02:53","date_gmt":"2025-09-05T21:02:53","guid":{"rendered":"https:\/\/golifeward.com\/de\/?p=3376"},"modified":"2025-09-08T10:06:26","modified_gmt":"2025-09-08T14:06:26","slug":"lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7","status":"publish","type":"post","link":"https:\/\/golifeward.com\/de\/blog\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\/","title":{"rendered":"Lifeward erh\u00e4lt CE-Kennzeichnung f\u00fcr das pers\u00f6nliche Exoskelett ReWalk 7"},"content":{"rendered":"\n<p><em><strong>Die siebte Generation des branchenf\u00fchrenden Exoskeletts ist jetzt in der Europ\u00e4ischen Union erh\u00e4ltlich<\/strong><\/em><\/p>\n\n\n\n<p>MARLBOROUGH, Massachusetts, YOKNEAM ILLIT, Israel, und Berlin, Deutschland 08. September 2025 \u2013 Lifeward Ltd. (Nasdaq: LFWD) (\u201eLifeward\u201d oder das \u201eUnternehmen\u201d), ein weltweit f\u00fchrendes Unternehmen im Bereich innovativer Medizintechnologie zur Verbesserung der Lebensqualit\u00e4t von Menschen mit k\u00f6rperlichen Einschr\u00e4nkungen oder Beeintr\u00e4chtigungen, gab heute bekannt, dass das Unternehmen die CE-Kennzeichnung f\u00fcr das ReWalk 7 Personal Exoskelett erhalten hat und somit die Zulassung f\u00fcr den Vertrieb in Europa vorliegt.<\/p>\n\n\n\n<p>Mit der siebten Generation des ReWalk 7 Personal Exoskeletts setzt Lifeward neue Ma\u00dfst\u00e4be in der Mobilit\u00e4tstechnologie: Ausgestattet mit innovativen Funktionen wie Cloud-Konnektivit\u00e4t, Steuerung per Knopfdruck, individuell anpassbaren Gehgeschwindigkeiten sowie einer nahtlosen Aktivierung f\u00fcr Treppen und Bordsteine, steht dieses Modell nun auch europ\u00e4ischen Nutzerinnen und Nutzern zur Verf\u00fcgung. Damit unterstreicht Lifeward seine Rolle als Vorreiter in der Entwicklung modernster Exoskelett-L\u00f6sungen und erweitert die M\u00f6glichkeiten f\u00fcr ein selbstbestimmtes Leben. Der europ\u00e4ische Vertrieb der Lifeward GmbH hat \u00fcber 40% der aktuellen ReWalk Personal Exoskelett Versorgungen des Gesamtunternehmens im Jahr 2025 erfolgreich abgeschlossen.<\/p>\n\n\n\n<p>\u201eDas ReWalk 7 er\u00f6ffnet gr\u00f6\u00dftm\u00f6gliche Unabh\u00e4ngigkeit, Selbstbestimmung und Mobilit\u00e4t f\u00fcr Menschen mit R\u00fcckenmarksverletzungen. Unsere Mission bei Lifeward ist es, Technologien zu entwickeln, die das Leben unserer Nutzerinnen und Nutzer nachhaltig ver\u00e4ndern\u201c, sagte Mark Grant, CEO von Lifeward Inc. \u201eMit der CE-Kennzeichnung k\u00f6nnen wir diesen Anspruch nun auch in Europa einl\u00f6sen und einen weiteren wichtigen Schritt hin zu echter Teilhabe und Lebensqualit\u00e4t erm\u00f6glichen.\u201c<\/p>\n\n\n\n<p>Das ReWalk Exoskelett ist als Hilfsmittel im Hilfsmittelverzeichnis des GKV-Spitzenverbandes gelistet und dient dem unmittelbaren Behinderungsausgleich. Mehrere Entscheidungen der Sozialgerichte und auch des <a href=\"https:\/\/golifeward.com\/de\/blog\/barmer-akzeptiert-zweitinstanzliches-urteil-des-lsg-nordrhein-westfalen-das-rewalk-exoskelett-dient-als-hilfsmittel-dem-unmittelbaren-behinderungsausgleich\/\">Landessozialgerichts NRW<\/a> haben dies bereits best\u00e4tigt. Somit kann das ReWalk Exoskelett beim Vorliegen der einschl\u00e4gigen Anspruchsvoraussetzungen von den behandelnden \u00c4rzten verordnet und von den Kostentr\u00e4gern erstattet werden. Damit haben querschnittgel\u00e4hmte Menschen, die die medizinischen Voraussetzungen erf\u00fcllen, Anspruch auf eine Versorgung mit dem Exoskelett. In Deutschland bestehen zudem Versorgungsvertr\u00e4ge mit mehreren Kostentr\u00e4gern. Hierzu z\u00e4hlen unter anderem die Techniker Krankenkasse, die Barmer und die DAK. Die Mitglieder der Deutschen Gesetzlichen Unfallversicherung (DGUV) haben das Angebot der Lifeward GmbH zur Versorgung ihrer Versicherten mit dem Rewalk Exoskelett bereits im Jahr 2020 offiziell angenommen.<\/p>\n\n\n\n<p>Fr\u00fchere Generationen des Rewalk Exoskeletts sind bereits seit 2010 auf dem europ\u00e4ischen Markt erh\u00e4ltlich, nachdem das Unternehmen erstmals eine CE-Kennzeichnung erhielt. Der europ\u00e4ische Markt wird durch den Vertrieb der Lifeward GmbH mit Sitz in Deutschland betreut \u2013 dem weltweit zweitgr\u00f6\u00dften Markt f\u00fcr ReWalk Exoskelette.<\/p>\n\n\n\n<p>Das ReWalk 7 erhielt im M\u00e4rz 2025 die <a href=\"https:\/\/golifeward.com\/blog\/fda-issues-clearance-for-rewalk-7-exoskeleton\/\">FDA-Zulassung<\/a>, der Verkaufsstart in den USAerfolgte im April. Bereits 2014 schrieb das Unternehmen Geschichte, als es die erste FDA-Zulassung in den USA f\u00fcr ein medizinisches Exoskelett f\u00fcr Menschen mit R\u00fcckenmarksverletzungen erhielt.<\/p>\n\n\n\n<p>Weitere Informationen zum Rewalk 7 finden sie <a href=\"https:\/\/golifeward.com\/de\/ppc-landing-page\/rewalk7de\/\">hier<\/a>.<\/p>\n\n\n\n<p><strong>\u00dcber Lifeward<\/strong><\/p>\n\n\n\n<p>Lifeward designt, entwickelt und vermarktet lebensver\u00e4ndernde L\u00f6sungen, die das gesamte Spektrum der k\u00f6rperlichen Rehabilitation und Genesung abdecken und nachweislich funktionelle und gesundheitliche Vorteile in klinischen Einrichtungen sowie im pers\u00f6nlichen Umfeld bieten. Unsere Mission bei Lifeward ist es, Innovationen voranzutreiben, um das Leben von Menschen mit k\u00f6rperlichen Einschr\u00e4nkungen oder Behinderungen zu ver\u00e4ndern.<\/p>\n\n\n\n<p>Wir haben uns verpflichtet, wegweisende L\u00f6sungen zu entwickeln, die es den Menschen erm\u00f6glichen, das zu tun, was sie lieben. Das Portfolio von Lifeward umfasst innovative Produkte wie das ReWalk Exoskelett, das AlterG Anti-Gravity System, sowie den ReStore Exo-Suit und das MyoCycle FES-System in USA.<\/p>\n\n\n\n<p>Lifeward wurde 2001 gegr\u00fcndet und hat Niederlassungen in den Vereinigten Staaten, Israel und Deutschland. Weitere Informationen \u00fcber das Lifeward-Portfolio finden Sie unter <a href=\"http:\/\/www.golifeward.com\/\">GoLifeward.com<\/a>\/de.<\/p>\n\n\n\n<p>Lifeward\u00ae, ReWalk\u00ae, ReStore\u00ae und Alter G\u00ae sind eingetragene Marken von Lifeward Ltd. und\/oder seinen Tochtergesellschaften.<\/p>\n\n\n\n<p><strong>Zukunftsgerichtete Aussagen<\/strong><\/p>\n\n\n\n<p>Neben historischen Informationen enth\u00e4lt diese Pressemitteilung zukunftsgerichtete Aussagen im Sinne des US-amerikanischen Private Securities Litigation Reform Act von 1995, Abschnitt 27A des US-amerikanischen Securities Act von 1933 und Abschnitt 21E des US-amerikanischen Securities Exchange Act von 1934. Solche zukunftsgerichteten Aussagen k\u00f6nnen Prognosen \u00fcber die zuk\u00fcnftige Leistung des Unternehmens und andere Aussagen enthalten, die keine historischen Fakten darstellen und in einigen F\u00e4llen durch W\u00f6rter wie \u201evoraussehen\u201c, \u201eannehmen\u201c, \u201eglauben\u201c, \u201efortsetzen\u201c, \u201ek\u00f6nnte\u201c, \u201esch\u00e4tzen\u201c, \u201eerwarten\u201c, \u201ebeabsichtigen\u201c, \u201ekann\u201c, \u201eplanen\u201c, \u201epotenziell\u201c, \u201evorhersagen\u201c, \u201eprognostizieren\u201c, \u201ezuk\u00fcnftig\u201c, \u201ewird\u201c, \u201esollte\u201c, \u201ew\u00fcrde\u201c, \u201eanstreben\u201c und \u00e4hnlichen Begriffen oder Formulierungen gekennzeichnet sein. Die in dieser Pressemitteilung enthaltenen zukunftsgerichteten Aussagen basieren auf den aktuellen Erwartungen des Managements, die Unsicherheiten, Risiken und Ver\u00e4nderungen der Umst\u00e4nde unterliegen, die schwer vorherzusagen sind und von denen viele au\u00dferhalb der Kontrolle des Unternehmens liegen. Wichtige Faktoren, die dazu f\u00fchren k\u00f6nnten, dass die tats\u00e4chlichen Ergebnisse des Unternehmens wesentlich von den in den zukunftsgerichteten Aussagen angegebenen Ergebnissen abweichen, sind unter anderem: die Akzeptanz des ReWalk 7 Personal Exoskeleton durch medizinisches Fachpersonal und Patienten; Unsicherheiten im Zusammenhang mit zuk\u00fcnftigen klinischen Studien und dem klinischen Entwicklungsprozess, dem Produktentwicklungsprozess und dem Zulassungspr\u00fcfungs- und -genehmigungsprozess der FDA; die F\u00e4higkeit des Unternehmens, \u00fcber ausreichende Mittel zu verf\u00fcgen, um bestimmte zuk\u00fcnftige Kapitalanforderungen zu erf\u00fcllen, was die Bem\u00fchungen des Unternehmens zur Entwicklung und Vermarktung bestehender und neuer Produkte beeintr\u00e4chtigen k\u00f6nnte; die F\u00e4higkeit des Unternehmens, seinen Ruf und die Marktakzeptanz seiner Produkte aufrechtzuerhalten und auszubauen; die F\u00e4higkeit des Unternehmens, von Drittzahlern, einschlie\u00dflich CMS, eine Erstattung f\u00fcr seine Produkte zu erhalten; die begrenzte Betriebsgeschichte des Unternehmens und seine F\u00e4higkeit, seine Vertriebs-, Marketing- und Schulungsinfrastruktur zu nutzen; die Erwartungen des Unternehmens hinsichtlich seines klinischen Forschungsprogramms und seiner klinischen Ergebnisse; die Erwartungen des Unternehmens hinsichtlich seines zuk\u00fcnftigen Wachstums, einschlie\u00dflich seiner F\u00e4higkeit, den Umsatz in seinen bestehenden geografischen M\u00e4rkten zu steigern und in neue M\u00e4rkte zu expandieren; die F\u00e4higkeit des Unternehmens, bestimmte Komponenten seiner Produkte von Drittanbietern zu beziehen und seinen Zugang zu seinen Produktherstellern aufrechtzuerhalten; die F\u00e4higkeit des Unternehmens, alle Schwierigkeiten zu bew\u00e4ltigen, die mit der Verlagerung der Produktion seiner AlterG Anti-Gravity-Systeme zu einem Vertragshersteller verbunden sind; die F\u00e4higkeit des Unternehmens, seine Produkte zu verbessern und neue Produkte zu entwickeln; die Einhaltung der Meldepflichten f\u00fcr Medizinprodukte durch das Unternehmen zur Meldung von unerw\u00fcnschten Ereignissen im Zusammenhang mit den Produkten des Unternehmens, die zu freiwilligen Korrekturma\u00dfnahmen oder Durchsetzungsma\u00dfnahmen wie obligatorischen R\u00fcckrufen f\u00fchren k\u00f6nnten, sowie die potenziellen Auswirkungen solcher unerw\u00fcnschten Ereignisse auf die F\u00e4higkeit des Unternehmens, seine Produkte zu vermarkten und zu verkaufen; die F\u00e4higkeit des Unternehmens, beh\u00f6rdliche Genehmigungen zu erhalten und aufrechtzuerhalten; die F\u00e4higkeit des Unternehmens, seinen geistigen Eigentum angemessen zu sch\u00fctzen und Verletzungen der geistigen Eigentumsrechte anderer zu vermeiden; das Risiko eines Cyberangriffs oder einer Verletzung der IT-Systeme des Unternehmens, die zu einer erheblichen St\u00f6rung seines Gesch\u00e4ftsbetriebs f\u00fchren k\u00f6nnten; die F\u00e4higkeit des Unternehmens, die Erl\u00f6se aus seinen Wertpapieremissionen effektiv zu nutzen; und andere Faktoren, die unter der \u00dcberschrift \u201eRisikofaktoren\u201d im Jahresbericht des Unternehmens auf Formular 10-K in der ge\u00e4nderten Fassung f\u00fcr das am 31. Dezember 2024 endende Gesch\u00e4ftsjahr, der bei der SEC eingereicht wurde, und in anderen Dokumenten, die anschlie\u00dfend bei der SEC eingereicht oder dieser zur Verf\u00fcgung gestellt wurden, er\u00f6rtert werden. Alle in dieser Pressemitteilung enthaltenen zukunftsgerichteten Aussagen gelten nur zum Zeitpunkt ihrer Ver\u00f6ffentlichung. Faktoren oder Ereignisse, die dazu f\u00fchren k\u00f6nnten, dass die tats\u00e4chlichen Ergebnisse des Unternehmens von den hierin enthaltenen Aussagen abweichen, k\u00f6nnen von Zeit zu Zeit auftreten, und es ist dem Unternehmen nicht m\u00f6glich, alle diese Faktoren oder Ereignisse vorherzusagen. Sofern nicht gesetzlich vorgeschrieben, \u00fcbernimmt das Unternehmen keine Verpflichtung, zukunftsgerichtete Aussagen \u00f6ffentlich zu aktualisieren, sei es aufgrund neuer Informationen, zuk\u00fcnftiger Entwicklungen oder aus anderen Gr\u00fcnden.<\/p>\n\n\n\n<p><strong>Lifeward Media Relations:<\/strong><\/p>\n\n\n\n<p>Kathleen O\u2019Donnell<br>VP Marketing &amp; New Business Development<br>Lifeward Ltd.<br>E-Mail: <a href=\"mailto:media@golifeward.com\">media@golifeward.com<\/a><\/p>\n\n\n\n<p><strong>Lifeward Investorenkontakt:<\/strong><\/p>\n\n\n\n<p>Almog Adar<br>Chief Financial Officer<br>Lifeward Ltd.<br>E-Mail: <a href=\"mailto:ir@golifeward.com\">ir@golifeward.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die siebte Generation des branchenf\u00fchrenden Exoskeletts ist jetzt in der Europ\u00e4ischen Union erh\u00e4ltlich MARLBOROUGH, Massachusetts, YOKNEAM ILLIT, Israel, und Berlin, Deutschland 08. September 2025 \u2013 Lifeward Ltd. (Nasdaq: LFWD) (\u201eLifeward\u201d oder das \u201eUnternehmen\u201d), ein weltweit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[85,84],"tags":[],"resource_type":[65],"medical_conditions":[],"related_products":[37],"audiences":[],"featured_resource_areas":[],"primary_resource_type":[73],"class_list":["post-3376","post","type-post","status-publish","format-standard","hentry","category-pressemitteilungen-de","category-medienberichte-de","resource_type-press-release","related_products-rewalk-product","primary_resource_type-press-release"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lifeward erh\u00e4lt CE-Kennzeichnung f\u00fcr das pers\u00f6nliche Exoskelett ReWalk 7 - Lifeward German Site<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/golifeward.com\/de\/blog\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lifeward erh\u00e4lt CE-Kennzeichnung f\u00fcr das pers\u00f6nliche Exoskelett ReWalk 7 - Lifeward German Site\" \/>\n<meta property=\"og:description\" content=\"Die siebte Generation des branchenf\u00fchrenden Exoskeletts ist jetzt in der Europ\u00e4ischen Union erh\u00e4ltlich MARLBOROUGH, Massachusetts, YOKNEAM ILLIT, Israel, und Berlin, Deutschland 08. September 2025 \u2013 Lifeward Ltd. (Nasdaq: LFWD) (\u201eLifeward\u201d oder das \u201eUnternehmen\u201d), ein weltweit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/golifeward.com\/de\/blog\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifeward German Site\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-05T21:02:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T14:06:26+00:00\" \/>\n<meta name=\"author\" content=\"raincastle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"raincastle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/golifeward.com\\\/de\\\/blog\\\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/golifeward.com\\\/de\\\/blog\\\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\\\/\"},\"author\":{\"name\":\"raincastle\",\"@id\":\"https:\\\/\\\/golifeward.com\\\/de\\\/#\\\/schema\\\/person\\\/f73b73d2fb8fbe32e1ba2a4d69397414\"},\"headline\":\"Lifeward erh\u00e4lt CE-Kennzeichnung f\u00fcr das pers\u00f6nliche Exoskelett ReWalk 7\",\"datePublished\":\"2025-09-05T21:02:53+00:00\",\"dateModified\":\"2025-09-08T14:06:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/golifeward.com\\\/de\\\/blog\\\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\\\/\"},\"wordCount\":1307,\"articleSection\":[\"Pressemitteilungen\",\"ReWalk in den Medien\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/golifeward.com\\\/de\\\/blog\\\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\\\/\",\"url\":\"https:\\\/\\\/golifeward.com\\\/de\\\/blog\\\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\\\/\",\"name\":\"Lifeward erh\u00e4lt CE-Kennzeichnung f\u00fcr das pers\u00f6nliche Exoskelett ReWalk 7 - Lifeward German Site\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/golifeward.com\\\/de\\\/#website\"},\"datePublished\":\"2025-09-05T21:02:53+00:00\",\"dateModified\":\"2025-09-08T14:06:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/golifeward.com\\\/de\\\/#\\\/schema\\\/person\\\/f73b73d2fb8fbe32e1ba2a4d69397414\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/golifeward.com\\\/de\\\/blog\\\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/golifeward.com\\\/de\\\/blog\\\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/golifeward.com\\\/de\\\/blog\\\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/golifeward.com\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lifeward erh\u00e4lt CE-Kennzeichnung f\u00fcr das pers\u00f6nliche Exoskelett ReWalk 7\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/golifeward.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/golifeward.com\\\/de\\\/\",\"name\":\"Lifeward German Site\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/golifeward.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/golifeward.com\\\/de\\\/#\\\/schema\\\/person\\\/f73b73d2fb8fbe32e1ba2a4d69397414\",\"name\":\"raincastle\",\"sameAs\":[\"https:\\\/\\\/lifeward.wpengine.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lifeward erh\u00e4lt CE-Kennzeichnung f\u00fcr das pers\u00f6nliche Exoskelett ReWalk 7 - Lifeward German Site","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/golifeward.com\/de\/blog\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\/","og_locale":"de_DE","og_type":"article","og_title":"Lifeward erh\u00e4lt CE-Kennzeichnung f\u00fcr das pers\u00f6nliche Exoskelett ReWalk 7 - Lifeward German Site","og_description":"Die siebte Generation des branchenf\u00fchrenden Exoskeletts ist jetzt in der Europ\u00e4ischen Union erh\u00e4ltlich MARLBOROUGH, Massachusetts, YOKNEAM ILLIT, Israel, und Berlin, Deutschland 08. September 2025 \u2013 Lifeward Ltd. (Nasdaq: LFWD) (\u201eLifeward\u201d oder das \u201eUnternehmen\u201d), ein weltweit [&hellip;]","og_url":"https:\/\/golifeward.com\/de\/blog\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\/","og_site_name":"Lifeward German Site","article_published_time":"2025-09-05T21:02:53+00:00","article_modified_time":"2025-09-08T14:06:26+00:00","author":"raincastle","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"raincastle","Gesch\u00e4tzte Lesezeit":"7 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/golifeward.com\/de\/blog\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\/#article","isPartOf":{"@id":"https:\/\/golifeward.com\/de\/blog\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\/"},"author":{"name":"raincastle","@id":"https:\/\/golifeward.com\/de\/#\/schema\/person\/f73b73d2fb8fbe32e1ba2a4d69397414"},"headline":"Lifeward erh\u00e4lt CE-Kennzeichnung f\u00fcr das pers\u00f6nliche Exoskelett ReWalk 7","datePublished":"2025-09-05T21:02:53+00:00","dateModified":"2025-09-08T14:06:26+00:00","mainEntityOfPage":{"@id":"https:\/\/golifeward.com\/de\/blog\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\/"},"wordCount":1307,"articleSection":["Pressemitteilungen","ReWalk in den Medien"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/golifeward.com\/de\/blog\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\/","url":"https:\/\/golifeward.com\/de\/blog\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\/","name":"Lifeward erh\u00e4lt CE-Kennzeichnung f\u00fcr das pers\u00f6nliche Exoskelett ReWalk 7 - Lifeward German Site","isPartOf":{"@id":"https:\/\/golifeward.com\/de\/#website"},"datePublished":"2025-09-05T21:02:53+00:00","dateModified":"2025-09-08T14:06:26+00:00","author":{"@id":"https:\/\/golifeward.com\/de\/#\/schema\/person\/f73b73d2fb8fbe32e1ba2a4d69397414"},"breadcrumb":{"@id":"https:\/\/golifeward.com\/de\/blog\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/golifeward.com\/de\/blog\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/golifeward.com\/de\/blog\/lifeward-erhaelt-ce-kennzeichnung-fuer-das-persoenliche-exoskelett-rewalk-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/golifeward.com\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Lifeward erh\u00e4lt CE-Kennzeichnung f\u00fcr das pers\u00f6nliche Exoskelett ReWalk 7"}]},{"@type":"WebSite","@id":"https:\/\/golifeward.com\/de\/#website","url":"https:\/\/golifeward.com\/de\/","name":"Lifeward German Site","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/golifeward.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/golifeward.com\/de\/#\/schema\/person\/f73b73d2fb8fbe32e1ba2a4d69397414","name":"raincastle","sameAs":["https:\/\/lifeward.wpengine.com"]}]}},"_links":{"self":[{"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/posts\/3376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/comments?post=3376"}],"version-history":[{"count":0,"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/posts\/3376\/revisions"}],"wp:attachment":[{"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/media?parent=3376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/categories?post=3376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/tags?post=3376"},{"taxonomy":"resource_type","embeddable":true,"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/resource_type?post=3376"},{"taxonomy":"medical_conditions","embeddable":true,"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/medical_conditions?post=3376"},{"taxonomy":"related_products","embeddable":true,"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/related_products?post=3376"},{"taxonomy":"audiences","embeddable":true,"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/audiences?post=3376"},{"taxonomy":"featured_resource_areas","embeddable":true,"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/featured_resource_areas?post=3376"},{"taxonomy":"primary_resource_type","embeddable":true,"href":"https:\/\/golifeward.com\/de\/wp-json\/wp\/v2\/primary_resource_type?post=3376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}